{"id":3851,"date":"1970-01-01T00:00:00","date_gmt":"2024-04-08T13:41:44","guid":{"rendered":"https:\/\/www.zendeq.com\/airport\/yaounde-airport\/"},"modified":"2024-06-03T12:56:32","modified_gmt":"2024-06-03T10:56:32","slug":"yaounde-airport","status":"publish","type":"airport","link":"https:\/\/www.zendeq.com\/de\/airport\/yaounde-airport\/","title":{"rendered":"Yaound\u00e9 Airport"},"content":{"rendered":"","protected":false},"parent":0,"template":"","class_list":["post-3851","airport","type-airport","status-publish","hentry","wpbf-post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yaound\u00e9 Airport &#8226; ZENDEQ<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zendeq.com\/de\/airport\/yaounde-airport\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yaound\u00e9 Airport &#8226; ZENDEQ\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zendeq.com\/de\/airport\/yaounde-airport\/\" \/>\n<meta property=\"og:site_name\" content=\"ZENDEQ\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-03T10:56:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zendeq.com\/wp-content\/uploads\/2021\/05\/Zendeq-logo-e1620744838610.png\" \/>\n\t<meta property=\"og:image:width\" content=\"398\" \/>\n\t<meta property=\"og:image:height\" content=\"146\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.zendeq.com\/wp-content\/uploads\/2021\/05\/Zendeq-logo-e1620744838610.png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zendeq.com\\\/de\\\/airport\\\/yaounde-airport\\\/\",\"url\":\"https:\\\/\\\/www.zendeq.com\\\/de\\\/airport\\\/yaounde-airport\\\/\",\"name\":\"Yaound\u00e9 Airport &#8226; ZENDEQ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zendeq.com\\\/de\\\/#website\"},\"datePublished\":\"2024-04-08T13:41:44+00:00\",\"dateModified\":\"2024-06-03T10:56:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zendeq.com\\\/de\\\/airport\\\/yaounde-airport\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zendeq.com\\\/de\\\/airport\\\/yaounde-airport\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zendeq.com\\\/de\\\/airport\\\/yaounde-airport\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zendeq.com\\\/de\\\/angebote-fuer-lagerhaeuser-anfordern\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Airports\",\"item\":\"https:\\\/\\\/www.zendeq.com\\\/de\\\/airport\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Yaound\u00e9 Airport\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zendeq.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.zendeq.com\\\/de\\\/\",\"name\":\"ZENDEQ\",\"description\":\"Supply Chain Collaboration Platform\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zendeq.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yaound\u00e9 Airport &#8226; ZENDEQ","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zendeq.com\/de\/airport\/yaounde-airport\/","og_locale":"de_DE","og_type":"article","og_title":"Yaound\u00e9 Airport &#8226; ZENDEQ","og_url":"https:\/\/www.zendeq.com\/de\/airport\/yaounde-airport\/","og_site_name":"ZENDEQ","article_modified_time":"2024-06-03T10:56:32+00:00","og_image":[{"width":398,"height":146,"url":"https:\/\/www.zendeq.com\/wp-content\/uploads\/2021\/05\/Zendeq-logo-e1620744838610.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/www.zendeq.com\/wp-content\/uploads\/2021\/05\/Zendeq-logo-e1620744838610.png","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zendeq.com\/de\/airport\/yaounde-airport\/","url":"https:\/\/www.zendeq.com\/de\/airport\/yaounde-airport\/","name":"Yaound\u00e9 Airport &#8226; ZENDEQ","isPartOf":{"@id":"https:\/\/www.zendeq.com\/de\/#website"},"datePublished":"2024-04-08T13:41:44+00:00","dateModified":"2024-06-03T10:56:32+00:00","breadcrumb":{"@id":"https:\/\/www.zendeq.com\/de\/airport\/yaounde-airport\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zendeq.com\/de\/airport\/yaounde-airport\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.zendeq.com\/de\/airport\/yaounde-airport\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zendeq.com\/de\/angebote-fuer-lagerhaeuser-anfordern\/"},{"@type":"ListItem","position":2,"name":"Airports","item":"https:\/\/www.zendeq.com\/de\/airport\/"},{"@type":"ListItem","position":3,"name":"Yaound\u00e9 Airport"}]},{"@type":"WebSite","@id":"https:\/\/www.zendeq.com\/de\/#website","url":"https:\/\/www.zendeq.com\/de\/","name":"ZENDEQ","description":"Supply Chain Collaboration Platform","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zendeq.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"airport_name_city":"Yaound\u00e9 Airport","city":"Yaounde","city_en":"Yaounde","city_nl":"Kameroen","iso_alpha2_country_code":"CM","iso_alpha3_country_code":"CMR","country_numeric_code":"120","country_en":"Cameroon","country":"Cameroon","country_nl":"Kameroen","country_es":"Camer\u00fan","country_de":"Kamerun","country_fr":"Cameroun","country_cn":"\u5580\u9ea6\u9686","iata_code":"YAO","icao_code":"FKKY","latitude":"3.83604001998901","longitude":"11.5235004425048","altitude_in_feet":"2464","port_type":"Airport","website":"","address":"","_links":{"self":[{"href":"https:\/\/www.zendeq.com\/de\/wp-json\/wp\/v2\/airport\/3851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zendeq.com\/de\/wp-json\/wp\/v2\/airport"}],"about":[{"href":"https:\/\/www.zendeq.com\/de\/wp-json\/wp\/v2\/types\/airport"}],"wp:attachment":[{"href":"https:\/\/www.zendeq.com\/de\/wp-json\/wp\/v2\/media?parent=3851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}