{"id":6904,"date":"1970-01-01T00:00:00","date_gmt":"2024-04-08T13:45:35","guid":{"rendered":"https:\/\/www.zendeq.com\/airport\/bouarfa-airport\/"},"modified":"2024-05-31T11:07:29","modified_gmt":"2024-05-31T09:07:29","slug":"bouarfa-airport","status":"publish","type":"airport","link":"https:\/\/www.zendeq.com\/nl\/airport\/bouarfa-airport\/","title":{"rendered":"Bouarfa Airport"},"content":{"rendered":"","protected":false},"parent":0,"template":"","class_list":["post-6904","airport","type-airport","status-publish","hentry","wpbf-post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bouarfa Airport &#8226; ZENDEQ<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zendeq.com\/nl\/airport\/bouarfa-airport\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bouarfa Airport &#8226; ZENDEQ\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zendeq.com\/nl\/airport\/bouarfa-airport\/\" \/>\n<meta property=\"og:site_name\" content=\"ZENDEQ\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-31T09:07:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zendeq.com\/wp-content\/uploads\/2021\/05\/Zendeq-logo-e1620744838610.png\" \/>\n\t<meta property=\"og:image:width\" content=\"398\" \/>\n\t<meta property=\"og:image:height\" content=\"146\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.zendeq.com\/wp-content\/uploads\/2021\/05\/Zendeq-logo-e1620744838610.png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/airport\\\/bouarfa-airport\\\/\",\"url\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/airport\\\/bouarfa-airport\\\/\",\"name\":\"Bouarfa Airport &#8226; ZENDEQ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/#website\"},\"datePublished\":\"2024-04-08T13:45:35+00:00\",\"dateModified\":\"2024-05-31T09:07:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/airport\\\/bouarfa-airport\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/airport\\\/bouarfa-airport\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/airport\\\/bouarfa-airport\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/offertes-voor-magazijnen-aanvragen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Airports\",\"item\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/airport\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bouarfa Airport\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/\",\"name\":\"ZENDEQ\",\"description\":\"Get quotes for any transport\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bouarfa Airport &#8226; ZENDEQ","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zendeq.com\/nl\/airport\/bouarfa-airport\/","og_locale":"nl_NL","og_type":"article","og_title":"Bouarfa Airport &#8226; ZENDEQ","og_url":"https:\/\/www.zendeq.com\/nl\/airport\/bouarfa-airport\/","og_site_name":"ZENDEQ","article_modified_time":"2024-05-31T09:07:29+00:00","og_image":[{"width":398,"height":146,"url":"https:\/\/www.zendeq.com\/wp-content\/uploads\/2021\/05\/Zendeq-logo-e1620744838610.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/www.zendeq.com\/wp-content\/uploads\/2021\/05\/Zendeq-logo-e1620744838610.png","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zendeq.com\/nl\/airport\/bouarfa-airport\/","url":"https:\/\/www.zendeq.com\/nl\/airport\/bouarfa-airport\/","name":"Bouarfa Airport &#8226; ZENDEQ","isPartOf":{"@id":"https:\/\/www.zendeq.com\/nl\/#website"},"datePublished":"2024-04-08T13:45:35+00:00","dateModified":"2024-05-31T09:07:29+00:00","breadcrumb":{"@id":"https:\/\/www.zendeq.com\/nl\/airport\/bouarfa-airport\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zendeq.com\/nl\/airport\/bouarfa-airport\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.zendeq.com\/nl\/airport\/bouarfa-airport\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zendeq.com\/nl\/offertes-voor-magazijnen-aanvragen\/"},{"@type":"ListItem","position":2,"name":"Airports","item":"https:\/\/www.zendeq.com\/nl\/airport\/"},{"@type":"ListItem","position":3,"name":"Bouarfa Airport"}]},{"@type":"WebSite","@id":"https:\/\/www.zendeq.com\/nl\/#website","url":"https:\/\/www.zendeq.com\/nl\/","name":"ZENDEQ","description":"Get quotes for any transport","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zendeq.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"airport_name_city":"Bouarfa Airport","city":"Bouarfa","city_en":"Bouarfa","city_nl":"Marokko","iso_alpha2_country_code":"MA","iso_alpha3_country_code":"MAR","country_numeric_code":"504","country_en":"Morocco","country":"Morocco","country_nl":"Marokko","country_es":"Marruecos","country_de":"Marokko","country_fr":"Maroc","country_cn":"\u6469\u6d1b\u54e5","iata_code":"UAR","icao_code":"GMFB","latitude":"32.514306","longitude":"-1.983056","altitude_in_feet":"3630","port_type":"Airport","website":"","address":"","_links":{"self":[{"href":"https:\/\/www.zendeq.com\/nl\/wp-json\/wp\/v2\/airport\/6904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zendeq.com\/nl\/wp-json\/wp\/v2\/airport"}],"about":[{"href":"https:\/\/www.zendeq.com\/nl\/wp-json\/wp\/v2\/types\/airport"}],"wp:attachment":[{"href":"https:\/\/www.zendeq.com\/nl\/wp-json\/wp\/v2\/media?parent=6904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}