{"id":16120,"date":"2024-04-10T22:24:55","date_gmt":"2024-04-10T20:24:55","guid":{"rendered":"https:\/\/www.zendeq.com\/seaport\/casablanca\/"},"modified":"2024-05-30T22:58:52","modified_gmt":"2024-05-30T20:58:52","slug":"casablanca","status":"publish","type":"seaport","link":"https:\/\/www.zendeq.com\/nl\/seaport\/casablanca\/","title":{"rendered":"Casablanca"},"content":{"rendered":"","protected":false},"template":"","class_list":["post-16120","seaport","type-seaport","status-publish","hentry","wpbf-post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casablanca &#8226; ZENDEQ<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zendeq.com\/nl\/seaport\/casablanca\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casablanca &#8226; ZENDEQ\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zendeq.com\/nl\/seaport\/casablanca\/\" \/>\n<meta property=\"og:site_name\" content=\"ZENDEQ\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-30T20:58:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/seaport\\\/casablanca\\\/\",\"url\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/seaport\\\/casablanca\\\/\",\"name\":\"Casablanca &#8226; ZENDEQ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/#website\"},\"datePublished\":\"2024-04-10T20:24:55+00:00\",\"dateModified\":\"2024-05-30T20:58:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/seaport\\\/casablanca\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/seaport\\\/casablanca\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/seaport\\\/casablanca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/offertes-voor-magazijnen-aanvragen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seaports\",\"item\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/seaport\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Casablanca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/\",\"name\":\"ZENDEQ\",\"description\":\"Get quotes for any transport\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zendeq.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casablanca &#8226; ZENDEQ","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zendeq.com\/nl\/seaport\/casablanca\/","og_locale":"nl_NL","og_type":"article","og_title":"Casablanca &#8226; ZENDEQ","og_url":"https:\/\/www.zendeq.com\/nl\/seaport\/casablanca\/","og_site_name":"ZENDEQ","article_modified_time":"2024-05-30T20:58:52+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zendeq.com\/nl\/seaport\/casablanca\/","url":"https:\/\/www.zendeq.com\/nl\/seaport\/casablanca\/","name":"Casablanca &#8226; ZENDEQ","isPartOf":{"@id":"https:\/\/www.zendeq.com\/nl\/#website"},"datePublished":"2024-04-10T20:24:55+00:00","dateModified":"2024-05-30T20:58:52+00:00","breadcrumb":{"@id":"https:\/\/www.zendeq.com\/nl\/seaport\/casablanca\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zendeq.com\/nl\/seaport\/casablanca\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.zendeq.com\/nl\/seaport\/casablanca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zendeq.com\/nl\/offertes-voor-magazijnen-aanvragen\/"},{"@type":"ListItem","position":2,"name":"Seaports","item":"https:\/\/www.zendeq.com\/nl\/seaport\/"},{"@type":"ListItem","position":3,"name":"Casablanca"}]},{"@type":"WebSite","@id":"https:\/\/www.zendeq.com\/nl\/#website","url":"https:\/\/www.zendeq.com\/nl\/","name":"ZENDEQ","description":"Get quotes for any transport","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zendeq.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"country":"Morocco","seaport_name_city":"Casablanca","city":"Casablanca","iso_alpha2_country_code":"MA","iso_alpha3_country_code":"MAR","country_numeric_code":"504","country_en":"Morocco","country_nl":"Marokko","country_es":"Marruecos","country_de":"Marokko","country_fr":"Maroc","country_cn":"\u6469\u6d1b\u54e5","lo_code":"CAS","code_un_locode":"MA CAS","latitude":"33\u00b0 36' N","longitude":"7\u00b0 37' W","port_type":"Seaport","website":"","address":"","city_en":"Casablanca","_links":{"self":[{"href":"https:\/\/www.zendeq.com\/nl\/wp-json\/wp\/v2\/seaport\/16120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zendeq.com\/nl\/wp-json\/wp\/v2\/seaport"}],"about":[{"href":"https:\/\/www.zendeq.com\/nl\/wp-json\/wp\/v2\/types\/seaport"}],"wp:attachment":[{"href":"https:\/\/www.zendeq.com\/nl\/wp-json\/wp\/v2\/media?parent=16120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}